{"id":6258,"date":"2025-03-31T11:27:18","date_gmt":"2025-03-31T11:27:18","guid":{"rendered":"https:\/\/indigitall.com\/?page_id=6258"},"modified":"2025-07-08T10:57:48","modified_gmt":"2025-07-08T10:57:48","slug":"politica-de-seguranca","status":"publish","type":"page","link":"https:\/\/indigitall.com\/br\/politica-de-seguranca\/","title":{"rendered":"Pol\u00edtica de Seguran\u00e7a"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-6258","page","type-page","status-publish","hentry"],"acf":{"flexible_content":[{"acf_fc_layout":"hero_utility_page","pretitle":"P\u00e1gina Legal","title":"Pol\u00edtica de Seguran\u00e7a"},{"acf_fc_layout":"legal_text","info_items":[{"title":"name","text":"SMART2ME, S.L"},{"title":"CIF","text":"B86653938"},{"title":"ADDRESS","text":"Paseo de la Castellana, 139, 28020 Madrid"},{"title":"PHONE","text":"+1 (213) 336-4050"},{"title":"EMAIL","text":"rgdp@indigitall.com"}],"content":"<strong>1. APROVA\u00c7\u00c3O E DATA DE VIG\u00caNCIA<\/strong>\r\n\r\nO texto foi aprovado em 19 de mar\u00e7o de 2025 pelo Diretor-Geral da SMART2ME, S.L (doravante INDIGITALL). Esta \"Pol\u00edtica de Seguran\u00e7a da Informa\u00e7\u00e3o\" (doravante, Pol\u00edtica) entrar\u00e1 em vigor na data de sua aprova\u00e7\u00e3o e permanecer\u00e1 vigente at\u00e9 ser substitu\u00edda por uma nova Pol\u00edtica.\r\n\r\n<strong>2. INTRODU\u00c7\u00c3O<\/strong>\r\n\r\nA INDIGITALL depende fortemente dos sistemas de TIC (Tecnologia da Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o) para atingir seus objetivos. Reconhece que a transforma\u00e7\u00e3o digital aumentou os riscos associados aos sistemas de informa\u00e7\u00e3o que suportam os servi\u00e7os p\u00fablicos. Como fornecedora do setor p\u00fablico, a INDIGITALL deve gerenciar adequadamente esses riscos.\r\n\r\nO objetivo desse gerenciamento de riscos \u00e9 proteger os sistemas de TIC contra danos acidentais ou intencionais que possam afetar a disponibilidade, integridade, confidencialidade, autenticidade ou rastreabilidade das informa\u00e7\u00f5es processadas pela INDIGITALL no \u00e2mbito dos servi\u00e7os do setor p\u00fablico, especificamente para centros residenciais e de sa\u00fade.\r\n\r\nOs sistemas de TIC devem ser protegidos contra amea\u00e7as em constante evolu\u00e7\u00e3o que podem impactar a confidencialidade, integridade, disponibilidade, uso pretendido e valor das informa\u00e7\u00f5es e servi\u00e7os. Para se defender dessas amea\u00e7as, deve existir uma estrat\u00e9gia que se adapte \u00e0s mudan\u00e7as ambientais para garantir a continuidade dos servi\u00e7os. Isso implica que os departamentos devem implementar as medidas de seguran\u00e7a m\u00ednimas exigidas pelo Esquema Nacional de Seguran\u00e7a (ENS), monitorar continuamente os n\u00edveis de desempenho dos servi\u00e7os, rastrear e analisar vulnerabilidades relatadas e preparar uma resposta eficaz a incidentes para garantir a continuidade dos servi\u00e7os.\r\n\r\nOs diferentes departamentos da INDIGITALL devem garantir que a seguran\u00e7a da TIC seja parte integrante de cada etapa do ciclo de vida do sistema, desde a concep\u00e7\u00e3o at\u00e9 a desativa\u00e7\u00e3o, incluindo desenvolvimento, aquisi\u00e7\u00e3o e atividades operacionais. Os requisitos de seguran\u00e7a e as necessidades financeiras devem ser identificados e incorporados no planejamento, nos pedidos de licita\u00e7\u00e3o e na contrata\u00e7\u00e3o de projetos de TIC.\r\n\r\nOs departamentos devem estar preparados para prevenir, detectar, responder e recuperar-se de incidentes, conforme estabelecido no Artigo 8 do ENS.\r\n\r\n<strong>3. \u00c2MBITO<\/strong>\r\n\r\n<strong>3.1 \u00c2mbito Subjetivo<\/strong>\r\n\r\nEsta Pol\u00edtica se aplica a todo o pessoal da INDIGITALL e a todas as pessoas ou entidades, internas ou externas, que prestam servi\u00e7os \u00e0 INDIGITALL, seja presencialmente ou remotamente.\r\n\r\n<strong>3.2 \u00c2mbito Objetivo<\/strong>\r\n\r\nEsta Pol\u00edtica se aplica aos sistemas de informa\u00e7\u00e3o da INDIGITALL relacionados aos servi\u00e7os da plataforma de \"marketing automation\" em um modelo SaaS.\r\n\r\n<strong>4. MARCO REGULAT\u00d3RIO<\/strong>\r\n\r\nA identifica\u00e7\u00e3o e manuten\u00e7\u00e3o do marco regulat\u00f3rio ser\u00e1 de responsabilidade do Respons\u00e1vel de Seguran\u00e7a da INDIGITALL e ser\u00e1 regida pelo procedimento de identifica\u00e7\u00e3o e avalia\u00e7\u00e3o dos requisitos legais. Isso incluir\u00e1 instru\u00e7\u00f5es t\u00e9cnicas obrigat\u00f3rias de seguran\u00e7a publicadas por meio de resolu\u00e7\u00f5es da Secretaria de Estado para Digitaliza\u00e7\u00e3o e Intelig\u00eancia Artificial do Minist\u00e9rio de Assuntos Econ\u00f4micos e Transforma\u00e7\u00e3o Digital ou pela entidade que assumir essas fun\u00e7\u00f5es.\r\n\r\nAl\u00e9m disso, o Respons\u00e1vel de Seguran\u00e7a ser\u00e1 encarregado de identificar as diretrizes de seguran\u00e7a do CCN aplic\u00e1veis \u00e0 melhoria da conformidade com o ENS.\r\n\r\n<strong>5. REQUISITOS M\u00cdNIMOS DE SEGURAN\u00c7A<\/strong>\r\n\r\nA Pol\u00edtica de Seguran\u00e7a da INDIGITALL regula a gest\u00e3o cont\u00ednua do processo de seguran\u00e7a. Esta Pol\u00edtica foi estabelecida de acordo com os princ\u00edpios b\u00e1sicos estabelecidos no Cap\u00edtulo II do ENS e foi desenvolvida considerando os seguintes requisitos m\u00ednimos de seguran\u00e7a:\r\n\r\na) Organiza\u00e7\u00e3o e implanta\u00e7\u00e3o do processo de seguran\u00e7a (art.13). b) An\u00e1lise e gerenciamento de riscos (art.14). c) Gest\u00e3o de pessoal (art.15). d) Profissionalismo (art.16). e) Autoriza\u00e7\u00e3o e controle de acesso (art.17). f) Prote\u00e7\u00e3o de instala\u00e7\u00f5es (art.18). g) Aquisi\u00e7\u00e3o de produtos de seguran\u00e7a e contrata\u00e7\u00e3o de servi\u00e7os de seguran\u00e7a (art.19). h) Privil\u00e9gio m\u00ednimo (art.20). i) Integridade e atualiza\u00e7\u00e3o dos sistemas (art.21). j) Prote\u00e7\u00e3o da informa\u00e7\u00e3o armazenada e transmitida (art.22). k) Preven\u00e7\u00e3o em rela\u00e7\u00e3o aos sistemas de informa\u00e7\u00e3o interconectados (art.23). l) Registro de atividades e detec\u00e7\u00e3o de c\u00f3digo malicioso (art.24). m) Incidentes de seguran\u00e7a (art.25). n) Continuidade dos neg\u00f3cios (art.26). \u00f1) Melhoria cont\u00ednua do processo de seguran\u00e7a (art.27).\r\n\r\nPara cumprir esses requisitos m\u00ednimos, a INDIGITALL aplicar\u00e1 as medidas de seguran\u00e7a do Anexo II do ENS, considerando:\r\n<ul>\r\n \t<li>Os ativos que constituem o sistema de informa\u00e7\u00e3o da INDIGITALL.<\/li>\r\n \t<li>A categoria de seguran\u00e7a do sistema, conforme previsto no Artigo 40.<\/li>\r\n \t<li>As decis\u00f5es tomadas para gerenciar os riscos identificados.<\/li>\r\n<\/ul>\r\n<p data-pm-slice=\"1 3 []\"><strong>6. PRINC\u00cdPIOS B\u00c1SICOS<\/strong><\/p>\r\nA Pol\u00edtica de Seguran\u00e7a da Informa\u00e7\u00e3o da INDIGITALL estabelece os seguintes princ\u00edpios fundamentais para o uso de sistemas de informa\u00e7\u00e3o:\r\n<ul data-spread=\"false\">\r\n \t<li><strong>Seguran\u00e7a como um processo integral:<\/strong> A seguran\u00e7a deve abranger todos os elementos humanos, materiais, t\u00e9cnicos, jur\u00eddicos e organizacionais relacionados aos sistemas de informa\u00e7\u00e3o.<\/li>\r\n \t<li><strong>Gest\u00e3o de riscos baseada em uma abordagem abrangente:<\/strong> A an\u00e1lise e a gest\u00e3o de riscos s\u00e3o essenciais para a seguran\u00e7a e devem ser realizadas de forma cont\u00ednua e atualizada regularmente.<\/li>\r\n \t<li><strong>Preven\u00e7\u00e3o, detec\u00e7\u00e3o, resposta e preserva\u00e7\u00e3o:<\/strong> A seguran\u00e7a do sistema de informa\u00e7\u00e3o deve incluir a\u00e7\u00f5es relacionadas \u00e0 preven\u00e7\u00e3o, detec\u00e7\u00e3o e resposta a incidentes.<\/li>\r\n \t<li><strong>M\u00faltiplas camadas de defesa:<\/strong> O sistema de informa\u00e7\u00e3o da INDIGITALL deve contar com uma estrat\u00e9gia de prote\u00e7\u00e3o baseada em m\u00faltiplos n\u00edveis de seguran\u00e7a.<\/li>\r\n \t<li><strong>Monitoramento cont\u00ednuo e reavalia\u00e7\u00e3o peri\u00f3dica:<\/strong> O monitoramento cont\u00ednuo permite detectar atividades ou comportamentos anormais e garantir uma resposta adequada.<\/li>\r\n<\/ul>\r\n<strong>7. OBJETIVOS DE SEGURAN\u00c7A DA INFORMA\u00c7\u00c3O<\/strong>\r\n\r\nA INDIGITALL estabelece os seguintes objetivos de seguran\u00e7a:\r\n<ul data-spread=\"false\">\r\n \t<li><strong>Garantir a prote\u00e7\u00e3o da informa\u00e7\u00e3o.<\/strong><\/li>\r\n \t<li><strong>Seguran\u00e7a f\u00edsica:<\/strong> Os sistemas de informa\u00e7\u00e3o da INDIGITALL s\u00e3o mantidos em \u00e1reas seguras e protegidas por controles de acesso adequados.<\/li>\r\n \t<li><strong>Controle de acesso:<\/strong> O acesso aos ativos de informa\u00e7\u00e3o \u00e9 limitado por meio de mecanismos de identifica\u00e7\u00e3o, autentica\u00e7\u00e3o e autoriza\u00e7\u00e3o.<\/li>\r\n \t<li><strong>Aquisi\u00e7\u00e3o, desenvolvimento e manuten\u00e7\u00e3o de sistemas:<\/strong> A seguran\u00e7a \u00e9 considerada em todas as fases do ciclo de vida do sistema.<\/li>\r\n \t<li><strong>Garantir a continuidade dos servi\u00e7os:<\/strong> Procedimentos s\u00e3o implementados para garantir a disponibilidade do sistema e a continuidade dos neg\u00f3cios.<\/li>\r\n \t<li><strong>Prote\u00e7\u00e3o de dados:<\/strong> Medidas t\u00e9cnicas e organizacionais s\u00e3o adotadas para gerenciar os riscos associados ao processamento de dados pessoais.<\/li>\r\n \t<li><strong>Conformidade:<\/strong> A INDIGITALL assegura o cumprimento das regulamenta\u00e7\u00f5es de seguran\u00e7a da informa\u00e7\u00e3o aplic\u00e1veis.<\/li>\r\n<\/ul>\r\n<p data-pm-slice=\"1 1 []\"><strong>8. MISS\u00c3O<\/strong><\/p>\r\nFundada em fevereiro de 2013, a INDIGITALL busca transcender os limites digitais, personalizando cada campanha de marketing de acordo com as prefer\u00eancias individuais dos clientes em todos os canais digitais por meio da intelig\u00eancia artificial. Isso garante que cada intera\u00e7\u00e3o seja relevante e eficaz, promovendo conex\u00f5es aut\u00eanticas, como se cada cliente tivesse um assistente pessoal. O objetivo da INDIGITALL \u00e9 aumentar a competitividade empresarial por meio da transforma\u00e7\u00e3o digital e de ferramentas de automa\u00e7\u00e3o de marketing, impulsionando uma estrat\u00e9gia omnicanal e sustent\u00e1vel. A inova\u00e7\u00e3o tecnol\u00f3gica est\u00e1 no cerne da INDIGITALL.\r\n\r\n<strong>9. CUMPRIMENTO DOS ARTIGOS<\/strong>\r\n\r\nPara cumprir os artigos do Decreto Real 311\/2022, a INDIGITALL implementou diversas medidas de seguran\u00e7a proporcionais \u00e0 natureza das informa\u00e7\u00f5es e servi\u00e7os protegidos, levando em considera\u00e7\u00e3o a categoria dos sistemas afetados.\r\n\r\nO cumprimento dos artigos do ENS \u00e9 detalhado na \"Declara\u00e7\u00e3o de Aplicabilidade\".\r\n\r\n<strong>10. DESENVOLVIMENTO DA POL\u00cdTICA<\/strong>\r\n\r\nO Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o da INDIGITALL aprovou o desenvolvimento de um sistema de gest\u00e3o, que ser\u00e1 estabelecido, implementado, mantido e melhorado de acordo com os padr\u00f5es de seguran\u00e7a. Esse sistema ser\u00e1 adaptado e gerenciar\u00e1 os controles do Esquema Nacional de Seguran\u00e7a. O sistema ser\u00e1 documentado e gerar\u00e1 evid\u00eancias dos controles e do cumprimento dos objetivos estabelecidos pelo Comit\u00ea.\r\n\r\nUm procedimento de gest\u00e3o documental ser\u00e1 estabelecido para definir as diretrizes para a estrutura\u00e7\u00e3o da documenta\u00e7\u00e3o de seguran\u00e7a do sistema, sua gest\u00e3o e acesso.\r\n\r\nO Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o \u00e9 respons\u00e1vel pela revis\u00e3o anual desta Pol\u00edtica, propondo melhorias conforme necess\u00e1rio para aprova\u00e7\u00e3o pelo Diretor-Geral da INDIGITALL.\r\n\r\nEsta Pol\u00edtica de Seguran\u00e7a da Informa\u00e7\u00e3o \u00e9 obrigat\u00f3ria e est\u00e1 estruturada nos seguintes n\u00edveis hier\u00e1rquicos:\r\n<ul>\r\n \t<li><strong>Primeiro N\u00edvel:<\/strong> Pol\u00edtica de Seguran\u00e7a da Informa\u00e7\u00e3o.<\/li>\r\n \t<li><strong>Segundo N\u00edvel:<\/strong> Regulamentos de Seguran\u00e7a.<\/li>\r\n \t<li><strong>Terceiro N\u00edvel:<\/strong> Procedimentos de Seguran\u00e7a.<\/li>\r\n<\/ul>\r\nO Respons\u00e1vel pela Seguran\u00e7a da Informa\u00e7\u00e3o (CISO), com o apoio da \u00e1rea de Qualidade, deve revisar este regulamento pelo menos anualmente, propondo melhorias conforme necess\u00e1rio.\r\n\r\nOs funcion\u00e1rios da INDIGITALL e as empresas terceirizadas devem estar familiarizados com esta Pol\u00edtica de Seguran\u00e7a, assim como com todos os regulamentos, procedimentos, instru\u00e7\u00f5es t\u00e9cnicas e demais documentos relevantes para suas fun\u00e7\u00f5es.\r\n\r\n<strong>10.1 Primeiro N\u00edvel Regulat\u00f3rio: Pol\u00edtica de Seguran\u00e7a da TIC<\/strong>\r\n\r\nA Pol\u00edtica de Seguran\u00e7a da TIC \u00e9 o instrumento normativo de mais alto n\u00edvel no quadro regulat\u00f3rio de seguran\u00e7a da INDIGITALL. Deve ser aprovada pelo Diretor-Geral da INDIGITALL.\r\n\r\n<strong>10.2 Segundo N\u00edvel Regulat\u00f3rio: Normas de Seguran\u00e7a da Informa\u00e7\u00e3o<\/strong>\r\n\r\nAs Normas de Seguran\u00e7a da TIC s\u00e3o instrumentos de n\u00edvel m\u00e9dio que cobrem \u00e1reas espec\u00edficas de seguran\u00e7a. A entidade respons\u00e1vel por sua aprova\u00e7\u00e3o \u00e9 o Comit\u00ea de Seguran\u00e7a da INDIGITALL.\r\n\r\n<strong>10.3 Terceiro N\u00edvel Regulat\u00f3rio: Procedimentos de Seguran\u00e7a da TIC<\/strong>\r\n\r\nOs Procedimentos de Seguran\u00e7a da TIC s\u00e3o instrumentos de n\u00edvel inferior, detalhados e aplic\u00e1veis a um escopo espec\u00edfico. O Respons\u00e1vel de Seguran\u00e7a \u00e9 encarregado de sua aprova\u00e7\u00e3o.\r\n\r\n<strong>11. ORGANIZA\u00c7\u00c3O DA SEGURAN\u00c7A<\/strong>\r\n\r\n<strong>11.1 Fun\u00e7\u00f5es e Perfis de Seguran\u00e7a<\/strong>\r\n\r\nPara garantir o cumprimento e a adapta\u00e7\u00e3o \u00e0s medidas exigidas por lei, foram criados pap\u00e9is e perfis de seguran\u00e7a, e os cargos ou \u00f3rg\u00e3os que os ocupar\u00e3o foram designados da seguinte forma:\r\n<ul>\r\n \t<li><strong>Respons\u00e1vel pela Informa\u00e7\u00e3o:<\/strong> Juan Carlos de Vela Benavides<\/li>\r\n \t<li><strong>Respons\u00e1vel pelo Servi\u00e7o:<\/strong> Xavier Omella Claparols<\/li>\r\n \t<li><strong>Respons\u00e1vel pela Seguran\u00e7a:<\/strong> Marcos Fort\u00fan Arranz<\/li>\r\n \t<li><strong>Respons\u00e1vel pelo Sistema:<\/strong> Jes\u00fas Moreira Rubio<\/li>\r\n<\/ul>\r\n<strong>11.2 Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o<\/strong>\r\n\r\nA INDIGITALL estabeleceu um Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o como um \u00f3rg\u00e3o colegiado, composto pelos seguintes membros:\r\n<ul>\r\n \t<li><strong>Diretor-Geral:<\/strong> Diretor-Geral da INDIGITALL.<\/li>\r\n \t<li><strong>Membros:<\/strong> Respons\u00e1vel pelo Servi\u00e7o, Respons\u00e1vel pelo Sistema, Respons\u00e1vel pela Seguran\u00e7a.<\/li>\r\n<\/ul>\r\nAl\u00e9m disso, outros membros da INDIGITALL podem ser incorporados ao trabalho do Comit\u00ea, incluindo grupos de trabalho especializados internos, externos ou mistos.\r\n\r\nO Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o realizar\u00e1 sess\u00f5es presenciais ou remotas semestralmente, com aviso pr\u00e9vio do Diretor-Geral do Comit\u00ea. Reuni\u00f5es extraordin\u00e1rias podem ser realizadas sempre que necess\u00e1rio devido a circunst\u00e2ncias espec\u00edficas.\r\n\r\n<strong>11.3 Responsabilidades associadas ao esquema ancional de seguran\u00e7a<\/strong>\r\n\r\nA seguir, s\u00e3o detalhadas e estabelecidas as fun\u00e7\u00f5es e responsabilidades de cada um dos pap\u00e9is de seguran\u00e7a do ENS:\r\n\r\n<strong>Fun\u00e7\u00f5es do Respons\u00e1vel pela Informa\u00e7\u00e3o e pelos Servi\u00e7os<\/strong>\r\n<ul>\r\n \t<li>Estabelecer e aprovar os requisitos de seguran\u00e7a aplic\u00e1veis ao servi\u00e7o e \u00e0 informa\u00e7\u00e3o dentro do marco estabelecido no Anexo II do ENS, conforme proposta ao Respons\u00e1vel de Seguran\u00e7a do ENS e\/ou Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o.<\/li>\r\n \t<li>Aceitar os n\u00edveis de risco residual que afetem o Servi\u00e7o e a Informa\u00e7\u00e3o.<\/li>\r\n<\/ul>\r\n<strong>Fun\u00e7\u00f5es do Respons\u00e1vel de Seguran\u00e7a (CISO\/RSF)<\/strong>\r\n<ul>\r\n \t<li>Manter e verificar o n\u00edvel adequado de seguran\u00e7a das informa\u00e7\u00f5es gerenciadas e dos servi\u00e7os eletr\u00f4nicos prestados pelos sistemas de informa\u00e7\u00e3o.<\/li>\r\n \t<li>Gerenciar, supervisionar e manter a seguran\u00e7a f\u00edsica das instala\u00e7\u00f5es da INDIGITALL.<\/li>\r\n \t<li>Promover a forma\u00e7\u00e3o e conscientiza\u00e7\u00e3o em mat\u00e9ria de seguran\u00e7a.<\/li>\r\n \t<li>Designar respons\u00e1veis pela execu\u00e7\u00e3o da an\u00e1lise de riscos, da declara\u00e7\u00e3o de aplicabilidade, identifica\u00e7\u00e3o de medidas de seguran\u00e7a, determina\u00e7\u00e3o das configura\u00e7\u00f5es necess\u00e1rias e elabora\u00e7\u00e3o da documenta\u00e7\u00e3o do sistema.<\/li>\r\n \t<li>Fornecer assessoria para a determina\u00e7\u00e3o da categoria do sistema, em colabora\u00e7\u00e3o com o Respons\u00e1vel pelo Sistema e\/ou Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o.<\/li>\r\n \t<li>Participar na elabora\u00e7\u00e3o e implementa\u00e7\u00e3o dos planos de melhoria da seguran\u00e7a e, quando necess\u00e1rio, nos planos de continuidade, procedendo \u00e0 sua valida\u00e7\u00e3o.<\/li>\r\n \t<li>Gerenciar as revis\u00f5es externas ou internas do sistema.<\/li>\r\n \t<li>Gerenciar os processos de certifica\u00e7\u00e3o.<\/li>\r\n \t<li>Submeter ao Comit\u00ea de Seguran\u00e7a a aprova\u00e7\u00e3o de mudan\u00e7as e outros requisitos do sistema.<\/li>\r\n<\/ul>\r\n<strong>Fun\u00e7\u00f5es do Respons\u00e1vel pelo Sistema<\/strong>\r\n<ul>\r\n \t<li>Suspender ou interromper o acesso \u00e0 informa\u00e7\u00e3o ou presta\u00e7\u00e3o de servi\u00e7o se identificar defici\u00eancias graves de seguran\u00e7a.<\/li>\r\n \t<li>Implementar e gerenciar os Sistemas de Informa\u00e7\u00e3o da INDIGITALL durante todo o seu ciclo de vida, incluindo a implementa\u00e7\u00e3o dos controles de ciberseguran\u00e7a, bem como sua opera\u00e7\u00e3o e verifica\u00e7\u00e3o de funcionamento adequado.<\/li>\r\n \t<li>Definir a topologia e a gest\u00e3o do Sistema de Informa\u00e7\u00e3o, estabelecendo crit\u00e9rios de uso e servi\u00e7os dispon\u00edveis.<\/li>\r\n \t<li>Assegurar que as medidas espec\u00edficas de seguran\u00e7a sejam integradas adequadamente dentro do marco geral de seguran\u00e7a.<\/li>\r\n \t<li>Colaborar com o Respons\u00e1vel de Seguran\u00e7a para a investiga\u00e7\u00e3o e resolu\u00e7\u00e3o de ciberincidentes que afetem os Sistemas de Informa\u00e7\u00e3o da INDIGITALL, aplicando os conhecimentos obtidos com a an\u00e1lise de incidentes passados para reduzir a probabilidade ou impacto de incidentes futuros.<\/li>\r\n \t<li>Realizar as fun\u00e7\u00f5es de administrador de seguran\u00e7a do sistema:\r\n<ul>\r\n \t<li>Gerenciar, configurar e atualizar hardware e software utilizados nos mecanismos e servi\u00e7os de seguran\u00e7a.<\/li>\r\n \t<li>Gerenciar autoriza\u00e7\u00f5es concedidas aos usu\u00e1rios do sistema, em particular os privil\u00e9gios concedidos, incluindo a monitoriza\u00e7\u00e3o da atividade no sistema e sua conformidade com as autoriza\u00e7\u00f5es concedidas.<\/li>\r\n \t<li>Aprovar altera\u00e7\u00f5es na configura\u00e7\u00e3o vigente do Sistema de Informa\u00e7\u00e3o.<\/li>\r\n \t<li>Garantir o cumprimento estrito dos controles de seguran\u00e7a estabelecidos.<\/li>\r\n \t<li>Garantir a aplica\u00e7\u00e3o dos procedimentos aprovados para a gest\u00e3o do Sistema de Informa\u00e7\u00e3o.<\/li>\r\n \t<li>Supervisionar a instala\u00e7\u00e3o, modifica\u00e7\u00e3o e melhoria de hardware e software para garantir que a seguran\u00e7a n\u00e3o seja comprometida e esteja sempre em conformidade com as autoriza\u00e7\u00f5es pertinentes.<\/li>\r\n \t<li>Monitorar o estado de seguran\u00e7a utilizando ferramentas de gest\u00e3o de eventos de seguran\u00e7a e mecanismos de auditoria t\u00e9cnica.<\/li>\r\n \t<li>Quando a complexidade do sistema justificar, o Respons\u00e1vel pelo Sistema poder\u00e1 designar respons\u00e1veis delegados com depend\u00eancia funcional direta, respons\u00e1veis por a\u00e7\u00f5es espec\u00edficas atribu\u00eddas a eles. Da mesma forma, poder\u00e1 delegar fun\u00e7\u00f5es espec\u00edficas de suas responsabilidades em outro(s) respons\u00e1vel(eis).<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<strong>Fun\u00e7\u00f5es do Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o<\/strong>\r\n\r\nO Comit\u00ea de Seguran\u00e7a ter\u00e1 as seguintes fun\u00e7\u00f5es:\r\n<ul>\r\n \t<li>Atender \u00e0s solicita\u00e7\u00f5es sobre Seguran\u00e7a da Informa\u00e7\u00e3o provenientes da Administra\u00e7\u00e3o e dos diferentes pap\u00e9is de seguran\u00e7a e\/ou \u00e1reas, informando regularmente sobre o estado da Seguran\u00e7a da Informa\u00e7\u00e3o.<\/li>\r\n \t<li>Fornecer assessoria em mat\u00e9ria de Seguran\u00e7a da Informa\u00e7\u00e3o.<\/li>\r\n \t<li>Resolver conflitos de responsabilidade entre as diferentes unidades administrativas.<\/li>\r\n \t<li>Promover a melhoria cont\u00ednua do sistema de gest\u00e3o da Seguran\u00e7a da Informa\u00e7\u00e3o, assegurando:\r\n<ul>\r\n \t<li>A coordena\u00e7\u00e3o dos esfor\u00e7os das diferentes \u00e1reas para garantir consist\u00eancia e alinhamento com a estrat\u00e9gia definida, evitando redund\u00e2ncias.<\/li>\r\n \t<li>A proposi\u00e7\u00e3o de planos de melhoria da Seguran\u00e7a da Informa\u00e7\u00e3o, incluindo or\u00e7amento correspondente, priorizando a\u00e7\u00f5es de seguran\u00e7a quando os recursos forem limitados.<\/li>\r\n \t<li>A considera\u00e7\u00e3o da Seguran\u00e7a da Informa\u00e7\u00e3o em todos os projetos, desde a especifica\u00e7\u00e3o inicial at\u00e9 a opera\u00e7\u00e3o, garantindo a cria\u00e7\u00e3o e utiliza\u00e7\u00e3o de servi\u00e7os horizontais que reduzam redund\u00e2ncias e promovam a uniformidade dos sistemas de TIC.<\/li>\r\n \t<li>O acompanhamento dos principais riscos residuais assumidos pela Administra\u00e7\u00e3o e a recomenda\u00e7\u00e3o de poss\u00edveis a\u00e7\u00f5es corretivas.<\/li>\r\n \t<li>O acompanhamento da gest\u00e3o de incidentes de seguran\u00e7a e a recomenda\u00e7\u00e3o de a\u00e7\u00f5es para mitiga\u00e7\u00e3o.<\/li>\r\n \t<li>A elabora\u00e7\u00e3o e revis\u00e3o regular da Pol\u00edtica de Seguran\u00e7a da Informa\u00e7\u00e3o para sua aprova\u00e7\u00e3o pelo \u00f3rg\u00e3o competente.<\/li>\r\n \t<li>A elabora\u00e7\u00e3o das normativas de Seguran\u00e7a da Informa\u00e7\u00e3o para aprova\u00e7\u00e3o em coordena\u00e7\u00e3o com a Dire\u00e7\u00e3o-Geral.<\/li>\r\n \t<li>A verifica\u00e7\u00e3o dos procedimentos de seguran\u00e7a da informa\u00e7\u00e3o e demais documenta\u00e7\u00f5es para aprova\u00e7\u00e3o.<\/li>\r\n \t<li>A elabora\u00e7\u00e3o de programas de forma\u00e7\u00e3o para capacitar e conscientizar o pessoal em Seguran\u00e7a da Informa\u00e7\u00e3o e prote\u00e7\u00e3o de dados pessoais.<\/li>\r\n \t<li>A defini\u00e7\u00e3o e aprova\u00e7\u00e3o dos requisitos de forma\u00e7\u00e3o e qualifica\u00e7\u00e3o de administradores, operadores e usu\u00e1rios no \u00e2mbito da Seguran\u00e7a da Informa\u00e7\u00e3o.<\/li>\r\n \t<li>A promo\u00e7\u00e3o da realiza\u00e7\u00e3o de auditorias peri\u00f3dicas do ENS e de prote\u00e7\u00e3o de dados para verificar o cumprimento das obriga\u00e7\u00f5es de seguran\u00e7a da informa\u00e7\u00e3o pela Administra\u00e7\u00e3o.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<strong>11.4 Procedimentos de Designa\u00e7\u00e3o<\/strong>\r\n\r\nA cria\u00e7\u00e3o do Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o, a nomea\u00e7\u00e3o de seus integrantes e a designa\u00e7\u00e3o dos Respons\u00e1veis identificados nesta Pol\u00edtica foram realizadas pelo Diretor-Geral da INDIGITALL e comunicadas \u00e0s partes interessadas.\r\n\r\nOs membros do Comit\u00ea, assim como os pap\u00e9is de seguran\u00e7a, ser\u00e3o revisados a cada tr\u00eas anos ou quando ocorrer uma vac\u00e2ncia.\r\n\r\n<strong>11.5 Matriz RACI: Matriz de Atribui\u00e7\u00e3o de Responsabilidades<\/strong>\r\n<table>\r\n<thead>\r\n<tr>\r\n<th><strong>Tarefa<\/strong><\/th>\r\n<th><strong>DG<\/strong><\/th>\r\n<th><strong>RI<\/strong><\/th>\r\n<th><strong>RS<\/strong><\/th>\r\n<th><strong>DPD<\/strong><\/th>\r\n<th><strong>CISO\/RSF<\/strong><\/th>\r\n<th><strong>CIO<\/strong><\/th>\r\n<\/tr>\r\n<\/thead>\r\n<tbody>\r\n<tr>\r\n<td>Pol\u00edtica de Seguran\u00e7a<\/td>\r\n<td>A<\/td>\r\n<td>C<\/td>\r\n<td>C<\/td>\r\n<td>C<\/td>\r\n<td>R<\/td>\r\n<td>C<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Determina\u00e7\u00e3o da categoria do Sistema<\/td>\r\n<td>C<\/td>\r\n<td>C<\/td>\r\n<td><\/td>\r\n<td><\/td>\r\n<td>A\/R<\/td>\r\n<td>C<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>An\u00e1lise de Riscos<\/td>\r\n<td><\/td>\r\n<td>I<\/td>\r\n<td>R<\/td>\r\n<td><\/td>\r\n<td>A\/R<\/td>\r\n<td>R<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Declara\u00e7\u00e3o de Aplicabilidade<\/td>\r\n<td><\/td>\r\n<td>I<\/td>\r\n<td>R<\/td>\r\n<td><\/td>\r\n<td>A\/R<\/td>\r\n<td>R<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Normas e Procedimentos de S.I<\/td>\r\n<td><\/td>\r\n<td>I<\/td>\r\n<td><\/td>\r\n<td><\/td>\r\n<td>A\/R<\/td>\r\n<td>R<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Resposta a incidentes de seguran\u00e7a<\/td>\r\n<td>I<\/td>\r\n<td>I<\/td>\r\n<td>C<\/td>\r\n<td>I<\/td>\r\n<td>A\/R<\/td>\r\n<td>R<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Seguran\u00e7a do ciclo de vida dos servi\u00e7os e sistemas de informa\u00e7\u00e3o<\/td>\r\n<td><\/td>\r\n<td><\/td>\r\n<td><\/td>\r\n<td>C<\/td>\r\n<td>A\/R<\/td>\r\n<td><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<strong>A (Accountable):<\/strong> Respons\u00e1vel pela decis\u00e3o final, autoriza e aprova.\r\n\r\n<strong>R (Responsible):<\/strong> Respons\u00e1vel pela execu\u00e7\u00e3o do trabalho.\r\n\r\n<strong>C (Consulted):<\/strong> Consultado antes da tomada de decis\u00e3o.\r\n\r\n<strong>I (Informed):<\/strong> Informado sobre as decis\u00f5es tomadas.\r\n\r\n<strong>12. RESOLU\u00c7\u00c3O DE CONFLITOS<\/strong>\r\n\r\nO Comit\u00ea de Seguran\u00e7a da Informa\u00e7\u00e3o da INDIGITALL ser\u00e1 respons\u00e1vel pela resolu\u00e7\u00e3o de conflitos e\/ou diverg\u00eancias de opini\u00e3o que possam surgir entre os pap\u00e9is de seguran\u00e7a.\r\n\r\n<strong>13. DADOS PESSOAIS<\/strong>\r\n\r\nA INDIGITALL somente processar\u00e1 dados pessoais quando forem adequados, pertinentes e n\u00e3o excessivos, e quando se relacionarem ao escopo e finalidades para as quais foram obtidos. Al\u00e9m disso, a INDIGITALL adotar\u00e1 as medidas t\u00e9cnicas e organizacionais necess\u00e1rias para cumprir as regulamenta\u00e7\u00f5es vigentes de Prote\u00e7\u00e3o de Dados, de acordo com a Pol\u00edtica de Prote\u00e7\u00e3o de Dados Pessoais aprovada pela Presid\u00eancia da INDIGITALL.\r\n\r\nEm conformidade com o Regulamento (UE) 2016\/679 do Parlamento Europeu e do Conselho, de 27 de abril de 2016, sobre a prote\u00e7\u00e3o de pessoas f\u00edsicas no que diz respeito ao processamento de dados pessoais e \u00e0 livre circula\u00e7\u00e3o desses dados (Regulamento Geral de Prote\u00e7\u00e3o de Dados - GDPR), e sua transposi\u00e7\u00e3o para a legisla\u00e7\u00e3o espanhola por meio da Lei Org\u00e2nica 3\/2018, de 5 de dezembro, sobre Prote\u00e7\u00e3o de Dados Pessoais e Garantia dos Direitos Digitais, foram implementadas medidas apropriadas, como a an\u00e1lise da legitimidade legal de cada atividade de processamento de dados, an\u00e1lise de riscos, avalia\u00e7\u00e3o de impacto quando o risco for alto, registro de atividades e nomea\u00e7\u00e3o de um Encarregado de Prote\u00e7\u00e3o de Dados.\r\n\r\n<strong>14. TERCEIROS<\/strong>\r\n\r\nAo prestar servi\u00e7os para outras organiza\u00e7\u00f5es ou lidar com informa\u00e7\u00f5es de terceiros, eles ser\u00e3o informados sobre esta Pol\u00edtica de Seguran\u00e7a da Informa\u00e7\u00e3o. A INDIGITALL definir\u00e1 e aprovar\u00e1 os canais de coordena\u00e7\u00e3o da informa\u00e7\u00e3o e os procedimentos de a\u00e7\u00e3o para responder a incidentes de seguran\u00e7a, bem como outras atividades relacionadas \u00e0 seguran\u00e7a realizadas em colabora\u00e7\u00e3o com outras entidades.\r\n\r\nCaso a INDIGITALL utilize servi\u00e7os de terceiros ou compartilhe informa\u00e7\u00f5es com terceiros, eles ser\u00e3o informados sobre esta Pol\u00edtica de Seguran\u00e7a e as Normas de Seguran\u00e7a aplic\u00e1veis a esses servi\u00e7os ou informa\u00e7\u00f5es. Os terceiros estar\u00e3o sujeitos \u00e0s obriga\u00e7\u00f5es estabelecidas nos regulamentos mencionados, mantendo a capacidade de desenvolver seus pr\u00f3prios procedimentos operacionais para cumpri-los. Ser\u00e3o estabelecidos procedimentos espec\u00edficos para comunica\u00e7\u00e3o e resolu\u00e7\u00e3o de incidentes. Tamb\u00e9m ser\u00e1 garantido que os funcion\u00e1rios de terceiros sejam adequadamente treinados em seguran\u00e7a, pelo menos no n\u00edvel exigido por esta Pol\u00edtica de Seguran\u00e7a.\r\n\r\nAl\u00e9m disso, considerando a obriga\u00e7\u00e3o de cumprir as Instru\u00e7\u00f5es T\u00e9cnicas de Seguran\u00e7a estabelecidas na segunda disposi\u00e7\u00e3o adicional do Decreto Real 311\/2022, e em conformidade com a Resolu\u00e7\u00e3o de 13 de outubro de 2016 da Secretaria de Estado para Administra\u00e7\u00f5es P\u00fablicas, que aprova a Instru\u00e7\u00e3o T\u00e9cnica de Seguran\u00e7a para o cumprimento do Esquema Nacional de Seguran\u00e7a, exige-se que operadores do setor privado que prestam servi\u00e7os ou solu\u00e7\u00f5es para entidades p\u00fablicas sujeitas ao Esquema Nacional de Seguran\u00e7a apresentem a correspondente Declara\u00e7\u00e3o de Conformidade para sistemas de categoria B\u00c1SICA ou a Certifica\u00e7\u00e3o de Conformidade para sistemas de categoria M\u00c9DIA ou ALTA.\r\n\r\nCaso qualquer aspecto desta Pol\u00edtica de Seguran\u00e7a n\u00e3o possa ser cumprido por um terceiro conforme exigido nos par\u00e1grafos anteriores, ser\u00e1 necess\u00e1rio um relat\u00f3rio do Respons\u00e1vel pela Seguran\u00e7a do ENS especificando os riscos envolvidos e como ser\u00e3o gerenciados. Esse relat\u00f3rio dever\u00e1 ser aprovado pelos respons\u00e1veis pela informa\u00e7\u00e3o e pelos servi\u00e7os afetados antes de prosseguir.\r\n\r\n<strong>15. MELHORIA CONT\u00cdNUA<\/strong>\r\n\r\nA gest\u00e3o da seguran\u00e7a da informa\u00e7\u00e3o \u00e9 um processo em constante evolu\u00e7\u00e3o. Portanto, a INDIGITALL deve implementar um processo de melhoria cont\u00ednua, que incluir\u00e1, entre outras a\u00e7\u00f5es:\r\n<ul>\r\n \t<li>Revis\u00e3o da Pol\u00edtica de Seguran\u00e7a da Informa\u00e7\u00e3o.<\/li>\r\n \t<li>Revis\u00e3o dos servi\u00e7os e informa\u00e7\u00f5es e sua categoriza\u00e7\u00e3o.<\/li>\r\n \t<li>Execu\u00e7\u00e3o anual da an\u00e1lise de riscos.<\/li>\r\n \t<li>Condu\u00e7\u00e3o de auditorias internas e externas.<\/li>\r\n \t<li>Revis\u00e3o das medidas de seguran\u00e7a.<\/li>\r\n \t<li>Revis\u00e3o e atualiza\u00e7\u00e3o dos regulamentos e procedimentos.<\/li>\r\n<\/ul>\r\nPara a INDIGITALL, a gest\u00e3o adequada da seguran\u00e7a da informa\u00e7\u00e3o \u00e9 um desafio cont\u00ednuo e coletivo, essencial para a continuidade da organiza\u00e7\u00e3o.\r\n\r\nA p\u00e1gina\u00a0 \u00e9 o canal usado por partes externas para relatar incidentes de seguran\u00e7a.\r\n<p class=\"my-0\"><strong>Uso do formul\u00e1rio de contato para comunica\u00e7\u00f5es externas<\/strong><\/p>\r\n<p class=\"my-0\">A SMART2ME, S.L disponibiliza o formul\u00e1rio de contato em seu site como o canal oficial para que qualquer pessoa externa (clientes, usu\u00e1rios, parceiros de neg\u00f3cios e o p\u00fablico em geral) possa comunicar incidentes t\u00e9cnicos, falhas do sistema, preocupa\u00e7\u00f5es relacionadas \u00e0 prote\u00e7\u00e3o de dados, bem como poss\u00edveis descumprimentos de controles internos, pol\u00edticas corporativas ou princ\u00edpios \u00e9ticos da empresa.<\/p>\r\n<p class=\"my-0\">Todas as comunica\u00e7\u00f5es recebidas por meio deste formul\u00e1rio: <a href=\"https:\/\/indigitall.com\/br\/formulario-de-seguranca\/\">https:\/\/indigitall.com\/br\/formulario-de-seguranca\/<\/a> ser\u00e3o tratadas de forma confidencial, aplicando-se as garantias estabelecidas nesta Pol\u00edtica de Privacidade e, quando for o caso, as previstas no C\u00f3digo de Conduta e Pr\u00e1ticas Respons\u00e1veis da SMART2ME, S.L.<\/p>","head_col_1":"","head_col_2":"","head_col_3":"","head_col_4":"","cookies_table":null}],"hide_slider_blog":false,"slider_blog_custom_tag":null,"hide_mobile_fixed_buttons":false,"mobile_fixed_button_1":null,"mobile_fixed_button_2":null,"icon_mobile_fixed_button_2":"","download_ebook":false,"ebook_title":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Seguran\u00e7a - indigitall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indigitall.com\/br\/politica-de-seguranca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Seguran\u00e7a - indigitall\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indigitall.com\/br\/politica-de-seguranca\/\" \/>\n<meta property=\"og:site_name\" content=\"indigitall\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T10:57:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/politica-de-seguranca\\\/\",\"url\":\"https:\\\/\\\/indigitall.com\\\/br\\\/politica-de-seguranca\\\/\",\"name\":\"Pol\u00edtica de Seguran\u00e7a - indigitall\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/#website\"},\"datePublished\":\"2025-03-31T11:27:18+00:00\",\"dateModified\":\"2025-07-08T10:57:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/politica-de-seguranca\\\/#breadcrumb\"},\"inLanguage\":\"br-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indigitall.com\\\/br\\\/politica-de-seguranca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/politica-de-seguranca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/indigitall.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Seguran\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/indigitall.com\\\/br\\\/\",\"name\":\"indigitall\",\"description\":\"Because Every Interaction Matters\",\"publisher\":{\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indigitall.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"br-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/#organization\",\"name\":\"indigitall\",\"url\":\"https:\\\/\\\/indigitall.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"br-BR\",\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/indigitall.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_indigitall_notificacion.png\",\"contentUrl\":\"https:\\\/\\\/indigitall.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_indigitall_notificacion.png\",\"width\":434,\"height\":434,\"caption\":\"indigitall\"},\"image\":{\"@id\":\"https:\\\/\\\/indigitall.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Seguran\u00e7a - indigitall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indigitall.com\/br\/politica-de-seguranca\/","og_locale":"en_US","og_type":"article","og_title":"Pol\u00edtica de Seguran\u00e7a - indigitall","og_url":"https:\/\/indigitall.com\/br\/politica-de-seguranca\/","og_site_name":"indigitall","article_modified_time":"2025-07-08T10:57:48+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/indigitall.com\/br\/politica-de-seguranca\/","url":"https:\/\/indigitall.com\/br\/politica-de-seguranca\/","name":"Pol\u00edtica de Seguran\u00e7a - indigitall","isPartOf":{"@id":"https:\/\/indigitall.com\/br\/#website"},"datePublished":"2025-03-31T11:27:18+00:00","dateModified":"2025-07-08T10:57:48+00:00","breadcrumb":{"@id":"https:\/\/indigitall.com\/br\/politica-de-seguranca\/#breadcrumb"},"inLanguage":"br-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indigitall.com\/br\/politica-de-seguranca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/indigitall.com\/br\/politica-de-seguranca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/indigitall.com\/br\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Seguran\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/indigitall.com\/br\/#website","url":"https:\/\/indigitall.com\/br\/","name":"indigitall","description":"Because Every Interaction Matters","publisher":{"@id":"https:\/\/indigitall.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indigitall.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"br-BR"},{"@type":"Organization","@id":"https:\/\/indigitall.com\/br\/#organization","name":"indigitall","url":"https:\/\/indigitall.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"br-BR","@id":"https:\/\/indigitall.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/indigitall.com\/wp-content\/uploads\/2026\/06\/logo_indigitall_notificacion.png","contentUrl":"https:\/\/indigitall.com\/wp-content\/uploads\/2026\/06\/logo_indigitall_notificacion.png","width":434,"height":434,"caption":"indigitall"},"image":{"@id":"https:\/\/indigitall.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/pages\/6258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/comments?post=6258"}],"version-history":[{"count":4,"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/pages\/6258\/revisions"}],"predecessor-version":[{"id":8892,"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/pages\/6258\/revisions\/8892"}],"wp:attachment":[{"href":"https:\/\/indigitall.com\/br\/wp-json\/wp\/v2\/media?parent=6258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}